{"id":7639,"count":1,"description":"","link":"https:\/\/www.clubvillamar.com\/blog\/tag\/peratallada-villas\/","name":"peratallada villas","slug":"peratallada-villas","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>peratallada villas Archives - Club Villamar<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"peratallada villas Archives - Club Villamar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clubvillamar.com\/blog\/tag\/peratallada-villas\/\" \/>\n<meta property=\"og:site_name\" content=\"Club Villamar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ClubVillamarEN\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.clubvillamar.com\/blog\/tag\/peratallada-villas\/\",\"url\":\"https:\/\/www.clubvillamar.com\/blog\/tag\/peratallada-villas\/\",\"name\":\"peratallada villas Archives - Club Villamar\",\"isPartOf\":{\"@id\":\"https:\/\/www.clubvillamar.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.clubvillamar.com\/blog\/tag\/peratallada-villas\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.clubvillamar.com\/blog\/tag\/peratallada-villas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.clubvillamar.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"peratallada villas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.clubvillamar.com\/blog\/#website\",\"url\":\"https:\/\/www.clubvillamar.com\/blog\/\",\"name\":\"Club Villamar\",\"description\":\"Relax poolside at your private Spanish villa\",\"publisher\":{\"@id\":\"https:\/\/www.clubvillamar.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.clubvillamar.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.clubvillamar.com\/blog\/#organization\",\"name\":\"Club Villamar\",\"url\":\"https:\/\/www.clubvillamar.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.clubvillamar.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.clubvillamar.com\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg\",\"contentUrl\":\"https:\/\/www.clubvillamar.com\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Club Villamar\"},\"image\":{\"@id\":\"https:\/\/www.clubvillamar.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ClubVillamar\",\"https:\/\/twitter.com\/ClubVillamarEN\",\"https:\/\/www.instagram.com\/clubvillamar\/\",\"https:\/\/www.linkedin.com\/company\/club-villamar\/\",\"https:\/\/www.pinterest.com\/clubvillamaruk\/\",\"https:\/\/www.youtube.com\/user\/ClubVillamar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"peratallada villas Archives - Club Villamar","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"peratallada villas Archives - Club Villamar","og_url":"https:\/\/www.clubvillamar.com\/blog\/tag\/peratallada-villas\/","og_site_name":"Club Villamar","twitter_card":"summary_large_image","twitter_site":"@ClubVillamarEN","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.clubvillamar.com\/blog\/tag\/peratallada-villas\/","url":"https:\/\/www.clubvillamar.com\/blog\/tag\/peratallada-villas\/","name":"peratallada villas Archives - Club Villamar","isPartOf":{"@id":"https:\/\/www.clubvillamar.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.clubvillamar.com\/blog\/tag\/peratallada-villas\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.clubvillamar.com\/blog\/tag\/peratallada-villas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.clubvillamar.com\/blog\/"},{"@type":"ListItem","position":2,"name":"peratallada villas"}]},{"@type":"WebSite","@id":"https:\/\/www.clubvillamar.com\/blog\/#website","url":"https:\/\/www.clubvillamar.com\/blog\/","name":"Club Villamar","description":"Relax poolside at your private Spanish villa","publisher":{"@id":"https:\/\/www.clubvillamar.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clubvillamar.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.clubvillamar.com\/blog\/#organization","name":"Club Villamar","url":"https:\/\/www.clubvillamar.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.clubvillamar.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.clubvillamar.com\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg","contentUrl":"https:\/\/www.clubvillamar.com\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg","width":1000,"height":1000,"caption":"Club Villamar"},"image":{"@id":"https:\/\/www.clubvillamar.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ClubVillamar","https:\/\/twitter.com\/ClubVillamarEN","https:\/\/www.instagram.com\/clubvillamar\/","https:\/\/www.linkedin.com\/company\/club-villamar\/","https:\/\/www.pinterest.com\/clubvillamaruk\/","https:\/\/www.youtube.com\/user\/ClubVillamar"]}]}},"_links":{"self":[{"href":"https:\/\/www.clubvillamar.com\/blog\/wp-json\/wp\/v2\/tags\/7639"}],"collection":[{"href":"https:\/\/www.clubvillamar.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.clubvillamar.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.clubvillamar.com\/blog\/wp-json\/wp\/v2\/posts?tags=7639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}